{"id":12938,"date":"2018-06-13T16:47:30","date_gmt":"2018-06-13T14:47:30","guid":{"rendered":"http:\/\/www.cittadellaeditrice.com\/munera\/?p=12938"},"modified":"2018-06-13T16:47:30","modified_gmt":"2018-06-13T14:47:30","slug":"la-svolta-profetica-di-papa-francesco-virtu-storico-filosofiche-e-vizi-sistematici-di-una-biografia-intellettuale-m-borghesi-2","status":"publish","type":"post","link":"https:\/\/www.cittadellaeditrice.com\/munera\/la-svolta-profetica-di-papa-francesco-virtu-storico-filosofiche-e-vizi-sistematici-di-una-biografia-intellettuale-m-borghesi-2\/","title":{"rendered":"La svolta profetica di papa Francesco: virt\u00f9 storico-filosofiche e vizi sistematici di una biografia intellettuale (M. Borghesi) (\/2)"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p><a href=\"http:\/\/www.cittadellaeditrice.com\/munera\/wp-content\/uploads\/papa-professore2.jpg\"><img decoding=\"async\" loading=\"lazy\" class=\"alignnone size-full wp-image-12686\" alt=\"papa professore\" src=\"http:\/\/www.cittadellaeditrice.com\/munera\/wp-content\/uploads\/papa-professore2.jpg\" width=\"288\" height=\"197\" \/><\/a><\/p>\n<p>Romano Guardini, in un saggio giovanile dedicato al \u201cmetodo sistematico\u201d in liturgia, ha fatto una affermazione che risulta preziosa per leggere il lungo saggio di M. Borghesi, <i>Jorge Mario Bergoglio. Una biografia intellettuale<\/i> (Milano, Jaca Book, 2017): \u201cla storia ci dice che cosa \u00e8 stato; la sistematica che cosa deve essere\u201d. Nell\u2019ambito delle prospettive che si sono aperte, grazie al Convegno IHU, sulla \u201cSvolta profetica di papa Francesco\u201d &#8211; di cui ho parlato nel precedente post di questa serie &#8211; ho ritenuto di presentare una serie di volumi, che intendo leggere nella prospettiva dischiusa dal Convegno brasiliano. Dir\u00f2 di pi\u00f9: se non fossi stato a Porto Alegre, se non avessi sentito parlare teologi e storici di mezzo mondo sul tema, non mi sarei accorto di quanto \u00e8 importante una comprensione profonda, articolata ed equilibrata del pensiero di Francesco e della sua esigenza di profezia. Proprio perch\u00e9 l\u2019ho vista valorizzata, limitata o negata, sento l\u2019esigenza di comprenderla meglio.<\/p>\n<p>Aggiungo che il volume di Borghesi, dal quale comincio la mia presentazione \u2013 e cui seguiranno i volumi di Lafont, Faggioli e Huenermann \u2013 \u00e8 apparso, proprio nel Convegno IHU particolarmente importante, perch\u00e9 \u00e8 stato pubblicato l\u2019anno scorso in italiano, ma ha gi\u00e0 una traduzione portoghese e ne avr\u00e0 presto una inglese. Nella presentazione che se ne \u00e8 stata fatta al Convegno brasiliano, appariva chiaro l\u2019intento di chiedere al libro la delicatissima funzione di \u201cpresentare\u201d e \u201caccompagnare\u201d Francesco negli USA, che sperimentano ecclesialmente una grande difficolt\u00e0 nel recepirne serenamente e pienamente il magistero. La biografia di Borghesi dovrebbe, dunque, \u201crassicurare\u201d e \u201cgarantire\u201d il magistero di Francesco.<\/p>\n<p>Ho trovato piuttosto curiosa questa motivazione: ne capisco la esigenza, ma ne comprendo anche i grandi rischi. Per questo motivo ho voluto leggere con attenzione il testo di Borghesi e qui ne presento una recensione non completa, ma per punti salienti.<\/p>\n<p><i>L\u2019impianto, lo scopo e la struttura<\/i><\/p>\n<p>La struttura del volume consta di 7 capitoli, nei quali si vogliono recuperare, in ordine cronologico, tutte le \u201cfonti\u201d del pensiero di Bergoglio: Fessard e Guardini, Methol Ferr\u00e9 e De Certeau, De Lubac e Von Balthasar. Lo scavo nelle fonti, soprattutto argentine, che \u00e8 spesso di prima mano e quindi assai prezioso, mette in luce influenze e relazioni importanti, anche se, talora, lavora su \u201cfonti di fonti\u201d in modo non del tutto lineare. Cos\u00ec, pur lavorando in rapporto con molti \u201cteologi\u201d, il libro di Borghesi non si presenta come un progetto di lettura teologica, ma come un disegno storico e filosofico del profilo di J.M. Bergoglio. Per questo l\u2019approccio dell\u2019autore, come vedremo, corre il rischio di proiettare sull\u2019oggetto il proprio metodo: ossia di proporre \u201cil pensiero di Bergoglio&#8230;(che) viene a costituirsi come una <i>sinfonia degli opposti. <\/i>Una filosofia che si colloca nell\u2019alveo del cattolicesimo, inteso come <i>coincidentia oppositorum<\/i>\u201d (23). Borghesi, insomma, tende a trattare il \u201cpensiero di Bergoglio\u201d come una filosofia, e ne sposta il centro in un approccio mistico e sociale, che non pare interessato alla riforma della Chiesa. Questo mi sembra il limite sistematico di un approccio storicamente cos\u00ec fecondo. E\u2019 evidente che Borghesi \u00e8 interessato a \u201csalvare\u201d il cattolicesimo di Francesco e Francesco in quanto \u201ccattolico\u201d. Ma pretende di farlo in una presunta \u201cequidistanza\u201d tra conservatori e progressisti, con una genericit\u00e0 che non riesce ad essere davvero fedele a Francesco. Riconosce con valore che siamo di fronte al fatto che il \u201cpensiero mistico \u00e8 un pensiero aperto, che non chiude gli spiragli\u201d (26), ma tende a dimenticare e a rimuovere che questa \u201cmistica\u201d deve nutrire non solo il pensiero, ma anche la struttura ecclesiale, le forme del matrimonio, la formazione dei presbiteri, la vocazione dei battezzati, la relazione col mondo. Su questo Borghesi diventa spesso vago e generico. Vediamo perch\u00e9.<\/p>\n<p><i>I limiti sistematici di una indagine storico-filosofica<\/i><\/p>\n<p>Posso ora pi\u00f9 chiaramente individuare la tensione tra \u201cricostruzione storica di un pensiero\u201d, e presentazione sistematica del pensiero stesso. Qui a mio avviso emergono i tre limiti che condizionano pi\u00f9 pesantemente il volume, e che ora voglio presentare in modo sintetico:<\/p>\n<p>a) L\u2019approccio filosofico-antropologico, che \u00e8 del tutto opportuno e realmente fecondo, appare anche inevitabilmente unilaterale: non considerando lo spessore teologico, ecclesiologico, istituzionale delle questioni, Borghesi perde in profondit\u00e0 e tende ad una genericit\u00e0 di giudizio, che impedisce una comprensione reale delle questioni in gioco. Si consideri ad esempio l\u2019intento espresso all\u2019inizio del volume con queste parole: l\u2019autore vuole \u201csuperare il luogo comune della opposizione di Francesco a Benedetto XVI, patrocinato dai conservatori. In realt\u00e0 siamo di fronte a una diversit\u00e0 di stili e di accenti, non di contenuti\u201d (21). Per esprimere questo giudizio, proprio in questa forma, Borghesi deve sospendere del tutto una domanda \u201csistematica\u201d su Francesco e su Benedetto. Se ci limitiamo ad una indagine puramente filosofica e antropologica, possiamo forse anche concordare con Borghesi. Ma se entriamo nella articolazione sistematica dei contenuti teologici, senza limitarci alle formule del catechismo, allora dobbiamo necessariamente osservare che le differenze maggiori sono proprio sul piano del contenuto. Non per arrivare alla \u201ccontrapposizione conservatrice\u201d, ma per comprendere la \u201cdiscontinuit\u00e0 riformatrice\u201d, che in Borghesi evapora totalmente. La discontinuit\u00e0 non \u00e8 \u201ccedimento alle logiche antitetiche\u201d, ma esperienza obiettiva, da elaborare.<\/p>\n<p>b) In linea con questo primo limite, un secondo, che ne \u00e8 conseguenza, diventa altrettanto importante: per Francesco il Concilio Vaticano II \u00e8 stato l\u2019orizzonte di formazione e di comprensione della esperienza ecclesiale, religiosa e ministeriale. Nel volume di Borghesi il tema \u00e8 affidato ad alcune riflessioni di grande pregio proposte da Methol Ferr\u00e9, che riguardano per\u00f2 \u2013 come ovvio, dato l\u2019autore \u2013 una comprensione \u201cteoretica\u201d e \u201cfilosofica\u201d del Vaticano II, soprattutto in rapporto al protestantesimo e all\u2019illuminismo. Le conseguenze di questa \u201crilettura della Chiesa in rapporto alla modernit\u00e0\u201d, sono per\u00f2 spostate, in modo filosoficamente interessante, ma teologicamente molto arbitrario, sulle dipendenze di M. Ferr\u00e9 rispetto al filosofo italiano A. Del Noce. E questa mossa conduce, nella pagine successive, ad una rilettura del Vaticano II in termini di \u201crisorgimento cattolico\u201d che inevitabilmente conduce, non senza forzature piuttosto rilevanti, ad una esaltazione di papa Ratzinger per la quale, citando sempre citando Methol Ferr\u00e9,: \u201ccon Ratzinger si pu\u00f2 dispiegare una nuova modernit\u00e0 cattolica, come sviluppo di quella modernit\u00e0 che ha avuto nel Concilio Vaticano II la sua manifestazione pi\u00f9 totalizzante\u201d (191).<\/p>\n<p>c) Da ultimo, e quasi a sintesi di questi primi due aspetti \u2013 ossia della lettura <em>\u201cnon teologica\u201d<\/em> e della considerazione <em>\u201cnon ecclesiologica\u201d<\/em> del Vaticano II \u2013 deriva un terzo limite, per certi versi ancora pi\u00f9 grave. Intendo dire la dipendenza che Borghesi dimostra in molte pagine, da una <em>\u201capologetica ciellina\u201d<\/em> &#8211; ossia da una considerazione esagerata della influenza di Comunione e Liberazione su Francesco e sulla storia del post-concilio &#8211; che raggiunge culmini di esplicitazione quasi imbarazzanti. Vorrei limitarmi a citare due passi, che si trovano nel capitolo ultimo, quello dedicato a \u201cCristianesimo e mondo contemporaneo\u201d. Nella prima parte del capitolo, in cui si discute su <i>Amoris Laetitia<\/i>, la lettura riduttiva, che viene proposta del testo, per salvarlo dalle accuse dei conservatori, poggia su una lettura non teologica, ma istituzionale e diplomatica, offerta da Rocco Buttiglione (256ss). In altra occasione, accanto alla positiva valutazione del testo di Buttiglione, avevo gi\u00e0 osservato che difendere Francesco \u201csolo perch\u00e9 e in quanto\u201d ripete Giovanni Paolo II, senza uscire da quella impostazione, \u00e8 una strategia minimalista che non consente di comprendere il \u201cgesto profetico\u201d di Francesco, che rilegge in modo originale il rapporto tra dottrina, morale, diritto e pastorale, superando un modello ottocentesco europeo. Ma questo \u00e8 solo un piccolo segnale. Nello stesso capitolo, infatti, alcune pagine pi\u00f9 avanti, leggiamo una \u201cdifesa di Bergoglio\u201d che mi pare molto prossima ad una sfigurazione. Si inizia ricordando che Bergoglio aveva letto libri e scritto prefazioni a volumi di L. Giussani. Bene. Poi si aggiunge, gi\u00e0 calcando la mano, che \u201cnel suo dialogo con don Giussani Bergoglio mette a fuoco una serie di categorie che torneranno costantemente nel suo insegnamento\u201d (278) avvalorando una sorta di parallelismo tra Giussani e Von Balthasar (sic!). Ma la \u201cquadratura del cerchio\u201d viene costruita da Borghesi in due pagine successive, che sono rivelatrici di un metodo di indagine con un controllo sistematico troppo fragile, che diventa facilmente preda di una lettura ideologica e distorta, scientificamente ed ecclesialmente non accettabile. Cito per intero il brano, di cui propongo poi una adeguata intepretazione:<\/p>\n<pre>\u00a0\u201cNell\u2019arco di tempo che va dalla fine degli anni 90 ai primi del 2000 Bergoglio mette a fuoro le categorie che ritroveremo al centro del documento finale...di Aparecida, nel 2007. L\u2019idea di fondo \u00e8 data da una formula che Bergoglio trova esemplarmente descritta nel <i>Deus caritas est<\/i> di Benedetto XVI: \u2018 All\u2019inizio dell\u2019essere cristiano non c\u2019\u00e8 una decisione etica o una grande idea, bens\u00ec l\u2019incontro con un avvenimento, una Persona, che d\u00e0 alla vita un nuovo orizzonte, e con ci\u00f2 la direzione decisiva\u2019. E\u2019 la formula riportata nella <i>Introduzione<\/i> del documento conclusivo di <i>Aparecida<\/i>. Ha un sapore decisamente \u2018giussaniano\u2019...\u201d (280).<\/pre>\n<pre><\/pre>\n<p>La pretesa di trovare un \u201cpunto di continuit\u00e0 fondamentale\u201d tra Francesco e Benedetto in una frase che deriverebbe da Luigi Giussani \u00e8 una affermazione che dimostra molto chiaramente tanto le intenzioni apologetiche della biografia, quanto la fragilit\u00e0 degli argomenti teologici e scientifici che le sostengono. Come si fa a non riconoscere che quella frase, in quel contesto, deriva a Benedetto, e poi a Francesco, da una lunga e complessa tradizione, di riflessione teologica e di argomentazione sistematica, rispetto a cui L. Giussani, se considerato con oggettivit\u00e0 teologica, deve essere riconosciuto come semplicemente esterno, se non estraneo? Voler a tutti i costi ricondurre Francesco a Benedetto, ed entrambi a Giussani, costituisce un modo per frantendere gravemente due papi e per alimentare genealogie del tutto congetturali, al solo scopo di \u201ccalmare gli animi\u201d, di \u201crassicurare i dubbiosi\u201d e di avvalorare una lettura talmente continuista da fraintendere la \u201crivoluzione culturale\u201d e il \u201ccambio di paradigma\u201d richiesto da Francesco.<\/p>\n<p><i>Un Francesco imborghesito e pastorizzato: profilo o caricatura?<\/i><\/p>\n<p>Alla fine, sia pur con un interessante recupero di dati biografici e teorici, che resteranno come un obiettivo guadagno per la ricerca successiva, il lettore non pu\u00f2 non restare un poco deluso dall\u2019impianto sistematico dell\u2019opera di Borghesi, che tenta di avvalorare un continuismo tra papi e una subordinazione del teologico all\u2019antropologico che non coincide con la realt\u00e0 effettuale di papa Francesco. E\u2019 una \u201cipotesi su Francesco\u201d che non regge ad un esame rigoroso per due motivi:<\/p>\n<p>&#8211; E\u2019 un Francesco \u201cimborghesito\u201d &#8211; mi si conceda il gioco di parole &#8211; non solo perch\u00e9 sottoposto ad una rilettura di Borghesi troppo unilaterale, ma perch\u00e9 depurato da ogni istanza critica a livello teologico ed ecclesiologico. Viene reso del tutto compatibile con quella autoreferenzialit\u00e0 ecclesiale che Francesco stesso vuole invece superare e rimuovere, mediante la riforma della Chiesa.<\/p>\n<p>&#8211; E\u2019 un Francesco \u201cpastorizzato\u201d, il cui profilo di pastore, riferito solo ad un profilo mistico e spirituale, viene privato della istanza profetica, istituzionale, riformatrice, critica. Con un Francesco cos\u00ec pastorizzato non si fa alcun formaggio! Si pu\u00f2 solo bere un latte certo gustoso, ma con la sicurezza di \u201cnon ammalarsi\u201d, restando cattolici e ministri esattamente come prima!<\/p>\n<p>Alla fine, il profilo intellettuale elaborato nel testo, pur con tutta la sua ricchezza di dati, rischia di apparire, almeno parzialmente, come una caricatura. Non vorrei che, per salvaguardare l\u2019ordine pubblico ecclesiale e rinunciando alla profezia, noi fossimo costretti a ragionare non su persone reali, ma su versioni di comodo o su riduzioni al passato. Guardini sapeva bene che il racconto dei dati del passato \u00e8 condizione per sane sintesi sistematiche; ma sapeva anche che una visione sistematica adeguata \u00e8 a sua volta condizione per \u201cvedere i dati\u201d nella loro pienezza e complessit\u00e0. L\u2019impressione \u00e8 che Massimo Borghesi, nel suo lodevole impegno di ricostruzione storica e filosofica, ma condizionato da una sistematica teologica troppo unilaterale e troppo fragile, abbia trovato solo quei dati che erano funzionali alla propria teoria. E che questo abbia compromesso, purtroppo, la profilatura dell\u2019uomo, del prete, del gesuita, dell\u2019Arcivescovo e del papa Jorge Mario Bergoglio. La cui profezia e la cui originalit\u00e0, purtroppo, sembra restare, in larga parte, fuori da questa biografia.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Romano Guardini, in un saggio giovanile dedicato al \u201cmetodo sistematico\u201d in liturgia, ha fatto una affermazione che risulta preziosa per leggere il lungo saggio di M. Borghesi, Jorge Mario Bergoglio. Una biografia intellettuale (Milano,&#8230;<\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[50],"tags":[],"_links":{"self":[{"href":"https:\/\/www.cittadellaeditrice.com\/munera\/wp-json\/wp\/v2\/posts\/12938"}],"collection":[{"href":"https:\/\/www.cittadellaeditrice.com\/munera\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cittadellaeditrice.com\/munera\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cittadellaeditrice.com\/munera\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cittadellaeditrice.com\/munera\/wp-json\/wp\/v2\/comments?post=12938"}],"version-history":[{"count":6,"href":"https:\/\/www.cittadellaeditrice.com\/munera\/wp-json\/wp\/v2\/posts\/12938\/revisions"}],"predecessor-version":[{"id":12944,"href":"https:\/\/www.cittadellaeditrice.com\/munera\/wp-json\/wp\/v2\/posts\/12938\/revisions\/12944"}],"wp:attachment":[{"href":"https:\/\/www.cittadellaeditrice.com\/munera\/wp-json\/wp\/v2\/media?parent=12938"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cittadellaeditrice.com\/munera\/wp-json\/wp\/v2\/categories?post=12938"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cittadellaeditrice.com\/munera\/wp-json\/wp\/v2\/tags?post=12938"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}