{"id":11211,"date":"2016-10-27T08:01:30","date_gmt":"2016-10-27T06:01:30","guid":{"rendered":"http:\/\/www.cittadellaeditrice.com\/munera\/?p=11211"},"modified":"2019-02-06T12:20:15","modified_gmt":"2019-02-06T11:20:15","slug":"munera-32016","status":"publish","type":"post","link":"https:\/\/www.cittadellaeditrice.com\/munera\/munera-32016\/","title":{"rendered":"Munera 3\/2016"},"content":{"rendered":"<p style=\"text-align: center;\"><a href=\"http:\/\/www.cittadellaeditrice.com\/munera\/wp-content\/uploads\/copxhome-3-2016.jpg\"><img decoding=\"async\" loading=\"lazy\" class=\"alignnone size-full wp-image-11212\" alt=\"copxhome-3-2016\" src=\"http:\/\/www.cittadellaeditrice.com\/munera\/wp-content\/uploads\/copxhome-3-2016.jpg\" width=\"470\" height=\"321\" srcset=\"https:\/\/www.cittadellaeditrice.com\/munera\/wp-content\/uploads\/copxhome-3-2016.jpg 470w, https:\/\/www.cittadellaeditrice.com\/munera\/wp-content\/uploads\/copxhome-3-2016-300x204.jpg 300w\" sizes=\"(max-width: 470px) 100vw, 470px\" \/><\/a><\/p>\n<h5>Contenuti<\/h5>\n<p><a title=\"Munera 3\/2016 \u2013 Editoriale\" href=\"http:\/\/www.cittadellaeditrice.com\/munera\/tutti-gli-articoli\/munera-32016-editoriale\/\">Editoriale<\/a> [download gratuito]<\/p>\n<p>Marie-Jo Thiel \u00bb <a title=\"Munera 3\/2016 \u2013 Marie-Jo Thiel &gt;&gt; L\u2019Unione Europea e le sue aperture alla teologia\" href=\"http:\/\/www.cittadellaeditrice.com\/munera\/tutti-gli-articoli\/munera-32016-marie-jo-thiel-lunione-europea-e-le-sue-aperture-alla-teologia\/\">L\u2019Unione Europea e le sue aperture alla teologia<\/a><br \/>\nUn linguaggio nuovo per la Chiesa: leggendo Amoris laetitia \u00bb <a title=\"Munera 3\/2016 \u2013 Un linguaggio nuovo per la Chiesa: leggendo Amoris laetitia &gt;&gt; Intervista con Maria Cristina Bartolomei e Giacomo Rossi\" href=\"http:\/\/www.cittadellaeditrice.com\/munera\/tutti-gli-articoli\/munera-32016-un-linguaggio-nuovo-per-la-chiesa-leggendo-amoris-laetitia-intervista-con-maria-cristina-bartolomei-e-giacomo-rossi\/\">Intervista con Maria Cristina Bartolomei e Giacomo Rossi<\/a><br \/>\nPierre Bu\u0308hler\u00bb <a title=\"Munera 3\/2016 \u2013 Pierre B\u00fchler &gt;&gt; L\u2019Apocalisse nell\u2019opera pittorica di Friedrich D\u00fcrrenmatt\" href=\"http:\/\/www.cittadellaeditrice.com\/munera\/tutti-gli-articoli\/munera-32016-pierre-buhler-lapocalisse-nellopera-pittorica-di-friedrich-durrenmatt\/\">L\u2019Apocalisse nell\u2019opera pittorica di Friedrich Du\u0308rrenmatt<\/a><br \/>\nAndrea Michieli \u00bb <a title=\"Munera 3\/2016 \u2013 Andrea Michieli &gt;&gt; La \u00abcontroriforma\u00bb. La revisione costituzionale alla prova del referendum\" href=\"http:\/\/www.cittadellaeditrice.com\/munera\/tutti-gli-articoli\/munera-32016-andrea-michieli-la-controriforma-la-revisione-costituzionale-alla-prova-del-referendum\/\">La \u00abcontroriforma\u00bb. La revisione costituzionale alla prova del referendum<\/a><br \/>\nPiermarco Aroldi \u00bb<a title=\"Munera 3\/2016 \u2013 Piermarco Aroldi &gt;&gt; Tra educazione e mercato. Valore e valori della Children\u2019s Television\" href=\"http:\/\/www.cittadellaeditrice.com\/munera\/tutti-gli-articoli\/munera-32016-piermarco-aroldi-tra-educazione-e-mercato-valore-e-valori-della-childrens-television\/\"> Tra educazione e mercato. Valore e valori della Children\u2019s Television<\/a><br \/>\nStefano Biancu \u00bb <a title=\"Munera 3\/2016 \u2013 Stefano Biancu &gt;&gt; Giuseppe Lazzati e l\u2019idea di cultura\" href=\"http:\/\/www.cittadellaeditrice.com\/munera\/tutti-gli-articoli\/munera-32016-stefano-biancu-giuseppe-lazzati-e-lidea-di-cultura\/\">Giuseppe Lazzati e l\u2019idea di cultura<\/a><br \/>\nLuigi F. Pizzolato \u00bb <a title=\"Munera 3\/2016 \u2013 Luigi F. Pizzolato &gt;&gt; Se Ges\u00f9 fosse rimasto a Nazaret\" href=\"http:\/\/www.cittadellaeditrice.com\/munera\/tutti-gli-articoli\/munera-32016-luigi-f-pizzolato-se-gesu-fosse-rimasto-a-nazaret\/\">Se Gesu\u0300 fosse rimasto a Nazaret<\/a><br \/>\nPierantonio Frare e Marco Salvioli \u00bb <a title=\"Munera 3\/2016 \u2013 Pierantonio Frare e Marco Salvioli &gt;&gt; Prodigi di misericordia e forza del linguaggio. Sui capitoli XXI e XXIII dei Promessi sposi\" href=\"http:\/\/www.cittadellaeditrice.com\/munera\/tutti-gli-articoli\/munera-32016-pierantonio-frare-e-marco-salvioli-prodigi-di-misericordia-e-forza-del-linguaggio-sui-capitoli-xxi-e-xxiii-dei-promessi-sposi\/\">Prodigi di misericordia e forza del linguaggio.\u00a0Sui capitoli XXI e XXIII dei Promessi sposi<\/a><br \/>\nEmanuela Sabatini \u00bb <a title=\"Munera 3\/2016 \u2013 Emanuela Sabatini &gt;&gt; Il Mos\u00e8 e Aronne di Sch\u0153nberg nella messa in scena di Romeo Castellucci\" href=\"http:\/\/www.cittadellaeditrice.com\/munera\/tutti-gli-articoli\/munera-32016-emanuela-sabatini-il-mose-e-aronne-di-schoenberg-nella-messa-in-scena-di-romeo-castellucci\/\">Il Mose\u0300 e Aronne di Sch\u0153nberg nella messa in scena di Romeo Castellucci<\/a><\/p>\n<p><a style=\"line-height: 1.5em;\" title=\"Munera 3\/2016 \u2013 Segnalibro\" href=\"http:\/\/www.cittadellaeditrice.com\/munera\/tutti-gli-articoli\/munera-32016-segnalibro\/\">Segnalibro<\/a><span style=\"line-height: 1.5em;\"> [download gratuito]<\/span><\/p>\n<h5>Acquisti<\/h5>\n<table width=\"100%\">\n<tbody>\n<tr>\n<td style=\"text-align: center;\" width=\"25%\"><a href=\"http:\/\/www.cittadellaeditrice.com\/index.php?content=scheda&amp;id=1015&amp;action=add&amp;id=1015\" target=\"_blank\"><img decoding=\"async\" loading=\"lazy\" alt=\"ico_acquista_cartaceo\" src=\"http:\/\/www.cittadellaeditrice.com\/munera\/wp-content\/uploads\/ico_acquista_cartaceo.jpg\" width=\"54\" height=\"54\" \/><\/a> <a href=\"http:\/\/www.cittadellaeditrice.com\/index.php?content=scheda&amp;id=1015&amp;action=add&amp;id=1015\" target=\"_blank\"> Munera 3\/2016<\/a> <a href=\"http:\/\/www.cittadellaeditrice.com\/index.php?content=scheda&amp;id=1015&amp;action=add&amp;id=1015\" target=\"_blank\"> rivista cartacea<\/a><\/td>\n<td style=\"text-align: center;\" width=\"25%\"><a href=\"javascript:formcompra('669','1');\"><img decoding=\"async\" loading=\"lazy\" alt=\"ico_acquista_digitale\" src=\"http:\/\/www.cittadellaeditrice.com\/munera\/wp-content\/uploads\/ico_acquista_digitale.jpg\" width=\"54\" height=\"54\" \/><\/a> <a href=\"javascript:formcompra('669','1');\"> Munera 3\/2016<\/a> <a href=\"javascript:formcompra('669','1');\"> ebook (pdf)<\/a><\/td>\n<td style=\"text-align: center;\" width=\"25%\"><a href=\"http:\/\/www.cittadellaeditrice.com\/index.php?content=modulo_ordine&amp;id=767\" target=\"_blank\"><img decoding=\"async\" loading=\"lazy\" alt=\"ico_acquista_abbcartaceo\" src=\"http:\/\/www.cittadellaeditrice.com\/munera\/wp-content\/uploads\/ico_acquista_abbcartaceo.jpg\" width=\"54\" height=\"54\" \/><\/a> <a href=\"http:\/\/www.cittadellaeditrice.com\/index.php?content=modulo_ordine&amp;id=767\" target=\"_blank\"> Abbonamento<\/a> <a href=\"http:\/\/www.cittadellaeditrice.com\/index.php?content=modulo_ordine&amp;id=767\" target=\"_blank\"> rivista cartacea<\/a><\/td>\n<td style=\"text-align: center;\" width=\"25%\"><a title=\"Abbonamento\" href=\"http:\/\/www.cittadellaeditrice.com\/munera\/abbonamento\/\"><img decoding=\"async\" loading=\"lazy\" alt=\"ico_acquista_abbdigitale\" src=\"http:\/\/www.cittadellaeditrice.com\/munera\/wp-content\/uploads\/ico_acquista_abbdigitale.jpg\" width=\"54\" height=\"54\" \/><\/a> <a title=\"Abbonamento\" href=\"http:\/\/www.cittadellaeditrice.com\/munera\/abbonamento\/\"> Abbonamento<\/a> <a title=\"Abbonamento\" href=\"http:\/\/www.cittadellaeditrice.com\/munera\/abbonamento\/\"> ebook (pdf)<\/a><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><em>Per acquistare i singoli articoli clicca sui titoli dall&#8217;indice in alto<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Contenuti Editoriale [download gratuito] Marie-Jo Thiel \u00bb L\u2019Unione Europea e le sue aperture alla teologia Un linguaggio nuovo per la Chiesa: leggendo Amoris laetitia \u00bb Intervista con Maria Cristina Bartolomei e Giacomo Rossi Pierre Bu\u0308hler\u00bb&#8230;<\/p>\n","protected":false},"author":1,"featured_media":11213,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"gallery","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/www.cittadellaeditrice.com\/munera\/wp-json\/wp\/v2\/posts\/11211"}],"collection":[{"href":"https:\/\/www.cittadellaeditrice.com\/munera\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cittadellaeditrice.com\/munera\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cittadellaeditrice.com\/munera\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cittadellaeditrice.com\/munera\/wp-json\/wp\/v2\/comments?post=11211"}],"version-history":[{"count":4,"href":"https:\/\/www.cittadellaeditrice.com\/munera\/wp-json\/wp\/v2\/posts\/11211\/revisions"}],"predecessor-version":[{"id":11215,"href":"https:\/\/www.cittadellaeditrice.com\/munera\/wp-json\/wp\/v2\/posts\/11211\/revisions\/11215"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cittadellaeditrice.com\/munera\/wp-json\/wp\/v2\/media\/11213"}],"wp:attachment":[{"href":"https:\/\/www.cittadellaeditrice.com\/munera\/wp-json\/wp\/v2\/media?parent=11211"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cittadellaeditrice.com\/munera\/wp-json\/wp\/v2\/categories?post=11211"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cittadellaeditrice.com\/munera\/wp-json\/wp\/v2\/tags?post=11211"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}