{"id":10360,"date":"2016-03-07T14:57:40","date_gmt":"2016-03-07T13:57:40","guid":{"rendered":"http:\/\/www.cittadellaeditrice.com\/munera\/?p=10360"},"modified":"2016-03-07T14:57:40","modified_gmt":"2016-03-07T13:57:40","slug":"identikit-della-vi-istruzione-sulla-riforma-liturgica-tre-domande-chiave","status":"publish","type":"post","link":"https:\/\/www.cittadellaeditrice.com\/munera\/identikit-della-vi-istruzione-sulla-riforma-liturgica-tre-domande-chiave\/","title":{"rendered":"Identikit della VI Istruzione sulla Riforma Liturgica: tre domande-chiave"},"content":{"rendered":"<p><a href=\"http:\/\/www.cittadellaeditrice.com\/munera\/wp-content\/uploads\/IstruzioneVI.jpg\"><img decoding=\"async\" loading=\"lazy\" class=\"alignnone size-medium wp-image-10361\" alt=\"IstruzioneVI\" src=\"http:\/\/www.cittadellaeditrice.com\/munera\/wp-content\/uploads\/IstruzioneVI-215x300.jpg\" width=\"215\" height=\"300\" srcset=\"https:\/\/www.cittadellaeditrice.com\/munera\/wp-content\/uploads\/IstruzioneVI-215x300.jpg 215w, https:\/\/www.cittadellaeditrice.com\/munera\/wp-content\/uploads\/IstruzioneVI-734x1024.jpg 734w, https:\/\/www.cittadellaeditrice.com\/munera\/wp-content\/uploads\/IstruzioneVI.jpg 1008w\" sizes=\"(max-width: 215px) 100vw, 215px\" \/><\/a><\/p>\n<p>Come potrebbe essere una futura VI Istruzione per la attuazione della Riforma Liturgica? Per rispondere a questa domanda bisogna porre tre questioni, che possono essere sollevate solo dopo aver considerato la &#8220;storia&#8221; delle prime 5 istruzioni.<\/p>\n<p><strong>A. La storia delle prime 5 Istruzioni<\/strong><\/p>\n<p align=\"justify\"><span style=\"font-family: 'Times New Roman', serif\">L<\/span><span style=\"font-family: 'Times New Roman', serif\">e <\/span><span style=\"font-family: 'Times New Roman', serif\"><i>cinque istruzioni <\/i><\/span><span style=\"font-family: 'Times New Roman', serif\">segnano il cammino che, dal Vaticano II giunge fino a noi. Come \u00e8 evidente dalla semplice lettura delle date di questi interventi magisteriali, tre di essi si concentrano nell\u2019immediato post-concilio (1964-1970), accompagnando la primissima e delicatissima fase della attuazione, mentre le ultime due riguardano una fase diversa, molto pi\u00f9 prossima a noi:<\/span><\/p>\n<ol type=\"a\">\n<li>\n<p align=\"justify\"><span style=\"font-family: 'Times New Roman', serif\"><i>Inter oecumenici<\/i><\/span><span style=\"font-family: 'Times New Roman', serif\"> (26 settembre 1964)<\/span><\/p>\n<\/li>\n<\/ol>\n<p align=\"justify\"><span style=\"font-family: 'Times New Roman', serif\">E\u2019 la prima autorevole \u201cguida applicativa\u201d del dettato della Costituzione liturgica, che riprende in tutti i suoi numeri, dando una prima attuazione concreta sia ai criteri generali di attuazione della riforma, sia delle singole scelte da compiere circa l\u2019eucaristia, i sacramenti e i sacramentali, l\u2019Ufficio Divino e l\u2019architettura. Il documento \u00e8 caratterizzato dalla \u201cdoppia firma\u201d, ossia quella della Congregazione dei riti e quella del <\/span><span style=\"font-family: 'Times New Roman', serif\"><i>Consilium ad exequendam Constitutionem de Sacra Liturgia<\/i><\/span><span style=\"font-family: 'Times New Roman', serif\">, ossia dell\u2019organo istituito da Paolo VI, con il motu proprio <\/span><span style=\"font-family: 'Times New Roman', serif\"><i>Sacram Liturgiam<\/i><\/span><span style=\"font-family: 'Times New Roman', serif\">, del 25 gennaio 1964. Bisogna infine ricordare che il testo della prima istruzione fissava anche la storica data del 7 marzo 1965, prima domenica di quaresima, come inizio di una nuova prassi liturgica, per quanto ancora soltanto provvisoria.<\/span><\/p>\n<ol start=\"2\" type=\"a\">\n<li>\n<p align=\"justify\"><span style=\"font-family: 'Times New Roman', serif\"><i>Tres abhinc annos<\/i><\/span><span style=\"font-family: 'Times New Roman', serif\"> (4 maggio 1967) (insieme a <\/span><span style=\"font-family: 'Times New Roman', serif\"><i>Musicam sacram<\/i><\/span><span style=\"font-family: 'Times New Roman', serif\"> e <\/span><span style=\"font-family: 'Times New Roman', serif\"><i>Eucharisticum mysterium<\/i><\/span><\/p>\n<\/li>\n<\/ol>\n<p align=\"justify\"><span style=\"font-family: 'Times New Roman', serif\">Nel giro di tre mesi, e con la stessa formula della \u201cdoppia firma\u201d, viene pubblicata non solo la seconda Istruzione (4 maggio), ma anche l\u2019Istruzione <\/span><span style=\"font-family: 'Times New Roman', serif\"><i>Musicam Sacram<\/i><\/span><span style=\"font-family: 'Times New Roman', serif\"> (5 marzo) e l\u2019Istruzione <\/span><span style=\"font-family: 'Times New Roman', serif\"><i>Eucharisticum mysterium<\/i><\/span><span style=\"font-family: 'Times New Roman', serif\"> (25 maggio). Il testo sulla musica \u00e8, di fatto, una integrazione della prima Istruzione, che non ne aveva trattato. Mentre il testo sulla eucaristia si occupa semplicemente di armonizzare il culto eucaristico fuori della messa alla liturgia rinnovata. Quanto invece alla <\/span><span style=\"font-family: 'Times New Roman', serif\"><i>Instructio altera<\/i><\/span><span style=\"font-family: 'Times New Roman', serif\">, essa costituisce \u201cun doveroso ed energico richiamo\u201d affinch\u00e9 l\u2019attuazione della Riforma segua i criteri stabiliti dalla prima istruzione, intervenendo su singoli ambiti a seguito delle richieste di Vescovi e Ordinari. E\u2019 la attestazione di una serie di difficolt\u00e0 e anche di contestazioni della fase attuativa della riforma liturgica.<\/span><\/p>\n<ol start=\"3\" type=\"a\">\n<li>\n<p align=\"justify\"><span style=\"font-family: 'Times New Roman', serif\"><i>Liturgicae instaurationes<\/i><\/span><span style=\"font-family: 'Times New Roman', serif\"> (5 settembre 1970)<\/span><\/p>\n<\/li>\n<\/ol>\n<p align=\"justify\"><span style=\"font-family: 'Times New Roman', serif\">E\u2019 un documento di svolta. Il compiersi della riforma del Messale Romano e la fine della attivit\u00e0 del <\/span><span style=\"font-family: 'Times New Roman', serif\"><i>Consilium, <\/i><\/span><span style=\"font-family: 'Times New Roman', serif\">che viene integrato nella nuova struttura della Congregazione per il culto divino, segnano due tappe fondamentali per la recezione di SC. Da un lato, il documento censura gli estremi opposti nella attuazione della riforma ( coloro che \u201c<\/span><span style=\"font-family: 'Times New Roman', serif\"><i>veteris servandae traditionis causa, huiusmodi reformationes aegre acceperunt<\/i><\/span><span style=\"font-family: 'Times New Roman', serif\">\u201d, e quelli che \u201c<\/span><span style=\"font-family: 'Times New Roman', serif\"><i>ad privata incepta&#8230;ad inventiones et additiones vel ad ritus simpliciores devenerint<\/i><\/span><span style=\"font-family: 'Times New Roman', serif\">\u201d) , dall\u2019altro interviene su singole questioni (unit\u00e0 tra liturgia della Parola e liturgia eucaristica, l\u2019indole della preghiera sacerdotale, i limiti del servizio liturgico femminile, la traduzione dei testi, le possibilit\u00e0 di esperimenti, ecc.). Nei sei anni che vanno dalla prima alla terza istruzione al grande cammino compiuto corrispondono l\u2019emergere di tensioni e di difficolt\u00e0 nella recezione concreta del grande disegno di SC. Le accuse di \u201cdesacralizzazione\u201d e di \u201cbanalizzazione\u201d, ricevendo risposta, toccano un nervo scoperto della sensibilit\u00e0 ecclesiale del tempo.<\/span><\/p>\n<ol start=\"4\" type=\"a\">\n<li>\n<p align=\"justify\"><span style=\"font-family: 'Times New Roman', serif\"><i>Varietates legitimae<\/i><\/span><span style=\"font-family: 'Times New Roman', serif\"> (25 gennaio 1994)<\/span><\/p>\n<\/li>\n<\/ol>\n<p align=\"justify\"><span style=\"font-family: 'Times New Roman', serif\">Una generazione dopo: questo \u00e8 il lasso di tempo che trascorre prima della nuova Istruzione. Essa fotografa, immediatamente, una condizione nuova, segnata profondamente dal pontificato di Giovanni Paolo II e dal suo carattere \u201citinerante\u201d, che lo metteva a stretto contatto con la grande differenza di tradizioni e di culture di cui la Chiesa cattolica era espressione. L\u2019istruzione vuole interpretare SC riguardo a quell\u2019adattamento della Liturgia che il Concilio ha introdotto autorevolmente e che in quel momento si riteneva dovesse ricevere una adeguata procedura di attuazione, affinch\u00e9 la sensibilit\u00e0 dei fedeli nei diversi continenti e la autenticit\u00e0 del rito romano non subissero impoverimenti o alterazioni. Si deve notare, tuttavia, che gi\u00e0 in questo documento sono presenti alcuni criteri restrittivi, che, mirando a conservare la \u201cautenticit\u00e0\u201d del rito romano, inclinano a una interpretazione \u201cdifensiva\u201d e \u201capologetica\u201d di SC e del Concilio Vaticano II, che prender\u00e0 ancora maggior forza con la successiva e finora ultima Istruzione.<\/span><\/p>\n<ol start=\"5\" type=\"a\">\n<li>\n<p align=\"justify\"><span style=\"font-family: 'Times New Roman', serif\"><i>Liturgiam authenticam<\/i><\/span><span style=\"font-family: 'Times New Roman', serif\"> (28 marzo 2001)<\/span><\/p>\n<\/li>\n<\/ol>\n<p align=\"justify\"><span style=\"font-family: 'Times New Roman', serif\">Con l\u2019approvazione di questo testo, che mette al centro il tema della \u201cautenticit\u00e0\u201d della liturgia, intendendolo pressoch\u00e9 esclusivamente come <i>fedelt\u00e0 letterale delle traduzioni in lingua volgare alla profondit\u00e0 dottrinale del testo latino, base indispensabile dell\u2019unit\u00e0 del rito romano<\/i>. Si vuole impedire che vada perso il prezioso vocabolario tradizionale, e si affida alla omelia e alla catechesi il compito di illustrarne il contenuto, evitando che ci\u00f2 avvenga mediante traduzioni interpretative o parafrasi e senza pretendere che il testo tradotto si spieghi totalmente da s\u00e9, al punto da arrivare al rischio di impoverirlo.<\/span><\/p>\n<p align=\"justify\"><span style=\"font-family: 'Times New Roman', serif\">Q<\/span><span style=\"font-family: 'Times New Roman', serif\">uesta Istruzione corrisponde perfettamente ad una crisi di recezione del dettato di <em>Sacrosanctum Concilium<\/em>: <\/span><span style=\"font-family: 'Times New Roman', serif\">i<\/span><span style=\"font-family: 'Times New Roman', serif\">n questione non \u00e8 semplicemente il tema della traduzione, ma piuttosto la interpretazione della stessa natura \u201cpastorale\u201d del Concilio Vaticano II e l\u2019autorit\u00e0 con cui esso ha posto, apertamente, la differenza tra la sostanza della antica dottrina del <\/span><span style=\"font-family: 'Times New Roman', serif\"><i>depositum fidei <\/i><\/span><span style=\"font-family: 'Times New Roman', serif\">e la formulazione del suo rivestimento. Ne emerge una profonda incomprensione della urgenza e della inaggirabilit\u00e0 di questo compito. Che le lingue moderne diventino \u201ccalchi incomprensibili\u201d di una lingua che solo mediante il proprio rivestimento pu\u00f2 garantire ricchezza della dottrina sembra contraddire nel modo pi\u00f9 esplicito \u2013 mettendo a rischio anche i comuni criteri non solo del tradurre, ma del vivere \u2013 la esigenza per cui l\u2019unit\u00e0 della Chiesa non venga garantita da una singola \u201cformulazione\u201d, ma dalla sostanza della dottrina.<\/span><\/p>\n<p align=\"justify\"><span style=\"font-family: 'Times New Roman', serif\"><b>B. Le tre domande-chiave<\/b><\/span><\/p>\n<p align=\"justify\"><span style=\"font-family: 'Times New Roman', serif\">Dal racconto di questa storia, ecco allora emergere lo spazio nel quale possiamo e dobbiamo porre le \u201ctre domande\u201d, per impostare un percorso che ci porter\u00e0 ad una VI Istruzione. Qui mi limito a formulare le tre questioni, per aprire un ampio dibattito sul tema.<\/span><\/p>\n<p align=\"justify\"><span style=\"color: #222222\"><span style=\"font-family: 'Times New Roman', serif\"><span>a) <i>Quale bilancio possiamo fare della V Istruzione, dopo 15 anni dalla sua approvazione ed entrata in vigore?<\/i><\/span><\/span><\/span><\/p>\n<p><span style=\"color: #222222\"><span style=\"font-family: 'Times New Roman', serif\"><span>b) <i>Per quali ragioni <\/i><i>appare<\/i><i> urgente una &#8220;VI Istruzione\u201d per la attuazione della Riforma Liturgica?<\/i><\/span><\/span><\/span><\/p>\n<p><span style=\"color: #222222\"><span style=\"font-family: 'Times New Roman', serif\"><span>c) <i>Quali sono i contenuti fondamentali che una tale Istruzione dovrebbe prevedere?<\/i><\/span><\/span><\/span><\/p>\n<p>&nbsp;<\/p>\n<p align=\"justify\">\n","protected":false},"excerpt":{"rendered":"<p>Come potrebbe essere una futura VI Istruzione per la attuazione della Riforma Liturgica? Per rispondere a questa domanda bisogna porre tre questioni, che possono essere sollevate solo dopo aver considerato la &#8220;storia&#8221; delle prime 5&#8230;<\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[50],"tags":[],"_links":{"self":[{"href":"https:\/\/www.cittadellaeditrice.com\/munera\/wp-json\/wp\/v2\/posts\/10360"}],"collection":[{"href":"https:\/\/www.cittadellaeditrice.com\/munera\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cittadellaeditrice.com\/munera\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cittadellaeditrice.com\/munera\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cittadellaeditrice.com\/munera\/wp-json\/wp\/v2\/comments?post=10360"}],"version-history":[{"count":2,"href":"https:\/\/www.cittadellaeditrice.com\/munera\/wp-json\/wp\/v2\/posts\/10360\/revisions"}],"predecessor-version":[{"id":10363,"href":"https:\/\/www.cittadellaeditrice.com\/munera\/wp-json\/wp\/v2\/posts\/10360\/revisions\/10363"}],"wp:attachment":[{"href":"https:\/\/www.cittadellaeditrice.com\/munera\/wp-json\/wp\/v2\/media?parent=10360"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cittadellaeditrice.com\/munera\/wp-json\/wp\/v2\/categories?post=10360"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cittadellaeditrice.com\/munera\/wp-json\/wp\/v2\/tags?post=10360"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}